{"id":10846,"date":"2023-10-18T14:18:58","date_gmt":"2023-10-18T12:18:58","guid":{"rendered":"https:\/\/www.piovan.com\/?post_type=job&#038;p=10846"},"modified":"2026-02-27T16:30:40","modified_gmt":"2026-02-27T15:30:40","slug":"plc-software-engineer-br","status":"publish","type":"job","link":"https:\/\/www.piovan.com\/es\/job\/plc-software-engineer-br\/","title":{"rendered":"PLC software Engineer (B&#038;R)"},"content":{"rendered":"<p>Ricerchiamo un PLC Software Engineer per potenziamento del team.<\/p>\n<p>Il candidato ideale \u00e8 diplomato o laureato in ambito elettronico\/informatico o meccatronico e ha maturato un\u2019esperienza nel ruolo minima di 4-5 anni, preferibilmente in aziende operanti nel settore dell\u2019automazione industriale e\/o dei controlli automatici.<\/p>\n<p>Verr\u00e0 inserito all\u2019interno di un team di progettazione software legato ai controlli macchina e supervisione.<\/p>\n<p>Requisiti richiesti fondamentali:<\/p>\n<ul>\n<li>Buona padronanza del linguaggio di programmazione B&amp;R del settore automazione su piattaforme PLC commerciali<\/li>\n<li>Discreta esperienza nei bus di campo industriali (Profibus\/Profinet, Modbus-TCP, Powerlink, CANOpen, OPC-UA).<\/li>\n<\/ul>\n<p>Sono richieste intraprendenza, capacit\u00e0 organizzative e analitiche, nonch\u00e9 attitudine a lavorare in team.<\/p>\n<p>Completano il profilo una buona conoscenza dei sistemi elettromeccanici e\/o meccatronici, della lingua inglese e la disponibilit\u00e0 a brevi trasferte all\u2019estero.<\/p>\n<p>Sede di lavoro: S. Maria di Sala (Venezia).<\/p>\n<p>La ricerca \u00e8 rivolta a candidati d'ambo i sessi, i cui dati saranno trattati per finalit\u00e0 di selezione in base alla normativa vigente.<\/p>\n<p>&nbsp;<\/p>","protected":false},"author":17,"template":"","tags":[108],"acf":{"location":"S. Maria di Sala (VE) | Italia","job_region":"EMEA, CENTRAL ASIA & SAARC","latitude":45.51430355684666,"longitude":12.031143286058283,"question_1":"","question_2":"","question_3":"","internship":false,"external_url":"","job_id":"","adp_job_id":""},"yoast_head":"<title>PLC software Engineer (B&amp;R) - PiovanGroup<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PLC software Engineer (B&amp;R) - PiovanGroup\" \/>\n<meta property=\"og:description\" content=\"Ricerchiamo un PLC Software Engineer per potenziamento del team. Il candidato ideale \u00e8 diplomato o laureato in ambito elettronico\/informatico o meccatronico e ha maturato un\u2019esperienza nel ruolo minima di 4-5 anni, preferibilmente in aziende operanti nel settore dell\u2019automazione industriale e\/o dei controlli automatici. Verr\u00e0 inserito all\u2019interno di un team di progettazione software legato ai controlli macchina e supervisione. Requisiti richiesti fondamentali: Buona padronanza del linguaggio di programmazione B&amp;R del settore automazione su piattaforme PLC commerciali Discreta esperienza nei bus di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.piovan.com\/es\/job\/plc-software-engineer-br\/\" \/>\n<meta property=\"og:site_name\" content=\"PiovanGroup\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T15:30:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.piovan.com\/wp-content\/uploads\/Piovan_pos-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.piovan.com\/job\/plc-software-engineer-br\/\",\"url\":\"https:\/\/www.piovan.com\/job\/plc-software-engineer-br\/\",\"name\":\"PLC software Engineer (B&R) - PiovanGroup\",\"isPartOf\":{\"@id\":\"https:\/\/www.piovan.com\/#website\"},\"datePublished\":\"2023-10-18T12:18:58+00:00\",\"dateModified\":\"2026-02-27T15:30:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.piovan.com\/job\/plc-software-engineer-br\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.piovan.com\/job\/plc-software-engineer-br\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.piovan.com\/job\/plc-software-engineer-br\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.piovan.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PLC software Engineer (B&#038;R)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.piovan.com\/#website\",\"url\":\"https:\/\/www.piovan.com\/\",\"name\":\"PiovanGroup\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.piovan.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.piovan.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.piovan.com\/#organization\",\"name\":\"PiovanGroup\",\"url\":\"https:\/\/www.piovan.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.piovan.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.piovan.com\/wp-content\/uploads\/2021\/06\/logo@2x.png\",\"contentUrl\":\"https:\/\/www.piovan.com\/wp-content\/uploads\/2021\/06\/logo@2x.png\",\"width\":489,\"height\":78,\"caption\":\"PiovanGroup\"},\"image\":{\"@id\":\"https:\/\/www.piovan.com\/#\/schema\/logo\/image\/\"}}]}<\/script>","yoast_head_json":{"title":"PLC software Engineer (B&R) - PiovanGroup","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"PLC software Engineer (B&R) - PiovanGroup","og_description":"Ricerchiamo un PLC Software Engineer per potenziamento del team. Il candidato ideale \u00e8 diplomato o laureato in ambito elettronico\/informatico o meccatronico e ha maturato un\u2019esperienza nel ruolo minima di 4-5 anni, preferibilmente in aziende operanti nel settore dell\u2019automazione industriale e\/o dei controlli automatici. Verr\u00e0 inserito all\u2019interno di un team di progettazione software legato ai controlli macchina e supervisione. Requisiti richiesti fondamentali: Buona padronanza del linguaggio di programmazione B&amp;R del settore automazione su piattaforme PLC commerciali Discreta esperienza nei bus di [&hellip;]","og_url":"https:\/\/www.piovan.com\/es\/job\/plc-software-engineer-br\/","og_site_name":"PiovanGroup","article_modified_time":"2026-02-27T15:30:40+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.piovan.com\/wp-content\/uploads\/Piovan_pos-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.piovan.com\/job\/plc-software-engineer-br\/","url":"https:\/\/www.piovan.com\/job\/plc-software-engineer-br\/","name":"PLC software Engineer (B&R) - PiovanGroup","isPartOf":{"@id":"https:\/\/www.piovan.com\/#website"},"datePublished":"2023-10-18T12:18:58+00:00","dateModified":"2026-02-27T15:30:40+00:00","breadcrumb":{"@id":"https:\/\/www.piovan.com\/job\/plc-software-engineer-br\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.piovan.com\/job\/plc-software-engineer-br\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.piovan.com\/job\/plc-software-engineer-br\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.piovan.com\/"},{"@type":"ListItem","position":2,"name":"PLC software Engineer (B&#038;R)"}]},{"@type":"WebSite","@id":"https:\/\/www.piovan.com\/#website","url":"https:\/\/www.piovan.com\/","name":"PiovanGroup","description":"","publisher":{"@id":"https:\/\/www.piovan.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.piovan.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.piovan.com\/#organization","name":"PiovanGroup","url":"https:\/\/www.piovan.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.piovan.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.piovan.com\/wp-content\/uploads\/2021\/06\/logo@2x.png","contentUrl":"https:\/\/www.piovan.com\/wp-content\/uploads\/2021\/06\/logo@2x.png","width":489,"height":78,"caption":"PiovanGroup"},"image":{"@id":"https:\/\/www.piovan.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.piovan.com\/es\/wp-json\/wp\/v2\/job\/10846"}],"collection":[{"href":"https:\/\/www.piovan.com\/es\/wp-json\/wp\/v2\/job"}],"about":[{"href":"https:\/\/www.piovan.com\/es\/wp-json\/wp\/v2\/types\/job"}],"author":[{"embeddable":true,"href":"https:\/\/www.piovan.com\/es\/wp-json\/wp\/v2\/users\/17"}],"wp:attachment":[{"href":"https:\/\/www.piovan.com\/es\/wp-json\/wp\/v2\/media?parent=10846"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.piovan.com\/es\/wp-json\/wp\/v2\/tags?post=10846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}